{"id":811,"date":"2019-10-27T15:06:20","date_gmt":"2019-10-27T15:06:20","guid":{"rendered":"http:\/\/www.efikanutricion.es\/?p=811"},"modified":"2020-11-04T09:53:56","modified_gmt":"2020-11-04T09:53:56","slug":"tips-para-hacer-la-cesta-de-la-compra","status":"publish","type":"post","link":"https:\/\/www.efikanutricion.es\/index.php\/2019\/10\/27\/tips-para-hacer-la-cesta-de-la-compra\/","title":{"rendered":"Tips para hacer la cesta de la compra"},"content":{"rendered":"<p style=\"text-align: justify;\">Hoy os doy los trucos para hacer una compra inteligente, una compra saludable, que ayude al planeta y encima a ahorrar en nuestra econom\u00eda, es f\u00e1cil, el mejor truco de todos la organizaci\u00f3n, a pesar de tener poco tiempo e ir siempre corriendo podemos organizarnos, es la mejor manera.<\/p>\n<p style=\"text-align: justify;\">Tips:<\/p>\n<p style=\"text-align: justify;\">1.El m\u00e1s importante de todos para mi, es<strong> organizar y planificar<\/strong> que vamos a comer o sea <strong>el men\u00fa<\/strong>. Para mi lo ideal es ir una vez a la semana en vez de ir cada d\u00eda a hacer la compra, ahorras tiempo y por supuesto que dinero.<\/p>\n<p style=\"text-align: justify;\">2. En funci\u00f3n del tip anterior, <strong>haz la lista de la compra<\/strong> con todos los productos que vas a necesitar y sobretodo c\u00ed\u00f1ete a ella y no compres nada que no est\u00e9 en ella. Siempre cae algo extra que no necesitas y que sabes que eso va a subir el ticket de compra, no te dejes llevar por \u00abel por si acaso\u00bb, no sirve.<\/p>\n<p style=\"text-align: justify;\">3. <strong>Ves a la compra despu\u00e9s de comer algo y no con hambre<\/strong>, es lo peor, llenar\u00e1s la cesta de productos ultraprocesados, altos en grasas y az\u00facares, est\u00e1 comprobado.<\/p>\n<p style=\"text-align: justify;\">4. <strong>Lee las etiquetas<\/strong> para evitar comprar productos ultraprocesados y fijate en las cantidades <strong>mejor compra por kg o por unidad<\/strong>, enga\u00f1an mucho los precios, o <strong>mejor productos a granel.<\/strong><\/p>\n<p style=\"text-align: justify;\">5. <strong>Aprovecha productos a punto de caducar<\/strong> siempre y cuando en tu men\u00fa est\u00e9n para consumir pronto, <strong>suelen estar rebajados de precio<\/strong>.<\/p>\n<p style=\"text-align: justify;\">6. <strong>Compra productos de temporada y de km O<\/strong>.<\/p>\n<p style=\"text-align: justify;\">7. <strong>Usa una cesta<\/strong> <strong>y s\u00f3lo compra lo que necesites<\/strong>, ya que los carros son muy grandes y los hacen as\u00ed para que los llenes.<\/p>\n<p style=\"text-align: justify;\">8. <strong>No te olvides de llevar tus propias bolsas<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Es muy importante tenerlo en cuenta para poder comer bien y ser mas eficientes en nuestras compras.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Hoy os doy los trucos para hacer una compra inteligente, una compra saludable, que ayude al planeta y encima a ahorrar en nuestra econom\u00eda, es f\u00e1cil, el mejor truco de todos la organizaci\u00f3n, a pesar de tener poco tiempo e ir siempre corriendo podemos organizarnos, es la mejor manera. Tips: 1.El m\u00e1s importante de todos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":""},"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.efikanutricion.es\/index.php\/wp-json\/wp\/v2\/posts\/811"}],"collection":[{"href":"https:\/\/www.efikanutricion.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.efikanutricion.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.efikanutricion.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.efikanutricion.es\/index.php\/wp-json\/wp\/v2\/comments?post=811"}],"version-history":[{"count":3,"href":"https:\/\/www.efikanutricion.es\/index.php\/wp-json\/wp\/v2\/posts\/811\/revisions"}],"predecessor-version":[{"id":892,"href":"https:\/\/www.efikanutricion.es\/index.php\/wp-json\/wp\/v2\/posts\/811\/revisions\/892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.efikanutricion.es\/index.php\/wp-json\/wp\/v2\/media\/812"}],"wp:attachment":[{"href":"https:\/\/www.efikanutricion.es\/index.php\/wp-json\/wp\/v2\/media?parent=811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.efikanutricion.es\/index.php\/wp-json\/wp\/v2\/categories?post=811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.efikanutricion.es\/index.php\/wp-json\/wp\/v2\/tags?post=811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}